{"id":3577,"date":"2024-09-24T18:01:00","date_gmt":"2024-09-24T18:01:00","guid":{"rendered":"https:\/\/keruanima.com\/?p=3577"},"modified":"2024-09-25T07:25:58","modified_gmt":"2024-09-25T07:25:58","slug":"reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo","status":"publish","type":"post","link":"https:\/\/keruanima.com\/en\/marketing-digital\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\/","title":{"rendered":"Reduflaci\u00f3n y \u00abestiraflaci\u00f3n\u00bb: El gasto en alza perpetuo"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Hace poco me tope con una de esas recomendaciones de youtube de un canal que analiza el marketing y patrones oscuros que usan las marcas, este es el v\u00eddeo por si tienes curiosidad: <a href=\"https:\/\/www.youtube.com\/watch?v=lBObRVlPyng\" target=\"_blank\" rel=\"noopener nofollow\" title=\"\">https:\/\/www.youtube.com\/watch?v=lBObRVlPyng<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el describe como en los \u00faltimos a\u00f1os multitud de empresas se las han ingeniado para nunca salir perdiendio en ingresos y beneficios en tiempos de crisis y tambi\u00e9n tras estas crisis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo  interesante del v\u00eddeo es que refleja el modelo imperfecto que da forma a nuestra econom\u00eda, uno en el que una gran compa\u00f1\u00eda esta obligada a rendir cuentas a inversores y por tanto aportar un aumento paulatino de los beneficios lo que se traduce en una necesidad imperiosa por aumentar los ingresos incluso en periodos de recesi\u00f3n econ\u00f3mica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto nos lleva a ver practicas como la reduflaci\u00f3n, que como bien describe Trending Tony en su v\u00eddeo, se trata de reducir la cantidad de producto que se obtiene por el mismo precio que ya ten\u00eda dicho producto. Esta practica, como no, se realiza de tapadillo, muchas se disfrazan de redise\u00f1os del producto, mejoras de formula y estrat\u00e9gias de marketing similares. Es algo triste que como dise\u00f1adores nuestra labor en muchas ocasiones sea la de maquillar pr\u00e1cticas de baja moral como esta y aprovecho este humilde post para hacer un llamamiento a todo dise\u00f1ador que lo lea a mantener ante todo sus principios \u00e9ticos. Si bien estos principios a priori no dan de comer, al menos mantedr\u00e1n tu conciencia tranquila, desde luego el dise\u00f1o no se reduce a vender aquello que sabes que es una estafa, si bien podemos \u00abadornar\u00bb los productos para venderlos, al menos hagamoslo con aquellos que sean honestos o en los que realmente creamos que aportan algo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero me estoy dejando un termino, lamento el haberme ido por las ramas. El v\u00eddeo tambi\u00e9n menciona el termino estiraflaci\u00f3n, traducci\u00f3n del t\u00e9rmino ingl\u00e9s \u00abstretchflation\u00bb. Vendr\u00eda a ser otra forma de aumentar los beneficios por venta como la reduflaci\u00f3n, pero en este caso el aumentando la cantidad de producto para justificar un aumento del precio del mismo que no es muy proporcional ni justo, en el v\u00eddeo se pone un ejemplo de un producto que aumento 10% la cantidad que contenia mientras su precio aumento un 29%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con este panorama \u00bfqu\u00e9 soluciones nos quedan?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En primer lugar, como consumidores yo optar\u00eda por evitar el consumo y compra de este tipo de productos, si detectamos un producto que ha aumentado de manera desorbitada su precio o ha reducido significativamente su contenido sin que esto venga acompa\u00f1ado de una reducci\u00f3n proporcional del precio, lo mejor que podemos hacer es mostrar a la compa\u00f1\u00eda que como consumidores no entramos por el aro. Es la \u00fanica forma en la que la ley de oferta y demanda jugar\u00eda a favor del consumidor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tampoco debemos pasar por el aro los dise\u00f1adores, si bien es cierto que en ocasiones estas pr\u00e1cticas est\u00e1n m\u00e1s ligadas a estrat\u00e9gias de marketing que a dise\u00f1o, siempre van muy de la mano, porque acompa\u00f1ado de la decisi\u00f3n de marketing viene un redise\u00f1o del producto, una campa\u00f1a publicitaria enga\u00f1osa y otros aspectos que si nos salpican. Desde luego no abogo por una mentalidad de tibur\u00f3n y no tengo intenci\u00f3n de tenerla, no trato de empezar una discusi\u00f3n con aquellos que no tengan reparos morales y prioricen siempre su sustento antes que su \u00e9tica, todos hemos caido y cedido alguna vez en trabajos y proyectos que no nos agradaban mucho y los hemos hecho para poder seguir llevando comida al plato, pero considero que todo el mundo deber\u00eda tener un l\u00edmite y en mi caso tengo claro que un modelo de negocio que depende de estas pr\u00e1cticas no va a ser un cliente para el que quiera trabajar. Como se suele decir, hay muchos peces en el mar, esto tambi\u00e9n se aplica a tipos de clientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por supuesto, ser una marca y tener intenci\u00f3n de aumentar el precio de un producto es algo muy licito, pero esto debe ir acompa\u00f1ado de un aumento real de su valor y no de pedir m\u00e1s por menos sin realmente haber mejorado en nada el producto o la relaci\u00f3n con la marca y usando mentiras y estrategias de moralidad cuestionable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y por \u00faltimo, quienes tienen m\u00e1s poder para hacer que esto en el corto plazo son las instituciones, los gobiernos y en \u00faltima estancia las propias marcas. Se deber\u00eda vetar este tipo de practicas y las propias marcas deber\u00edan tener la decencia de ser honestas, la honestidad aunque parezca que no tambi\u00e9n es un valor a\u00f1adido y muy positivo, los consumidores que aprecien que la marca que consumen es honesta y clara, que no trata de enga\u00f1arlos, se convertir\u00e1n en verdaderos consumidores fieles. Es cierto que como marca cuesta trabajo labrarse una buena reputaci\u00f3n, pero a mi modo de ver merece la pena.<\/p>","protected":false},"excerpt":{"rendered":"<p>Analisis y cr\u00edtica a dos vertienes o metodolog\u00edas con las que las compa\u00f1\u00edas aumentan sus beneficios por venta de unidad de producto.<\/p>","protected":false},"author":1,"featured_media":3584,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[44,56],"tags":[46,177,60,47],"class_list":["post-3577","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing-digital","category-opinion-y-critica","tag-critica","tag-malas-estrategias","tag-marketing","tag-opinion"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Analisis y cr\u00edtica a dos vertienes o metodolog\u00edas con las que las compa\u00f1\u00edas aumentan sus beneficios por venta de unidad de producto.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Keruanima\"\/>\n\t<meta name=\"google-site-verification\" content=\"DLdPqYVuvlPaTjY91_F7mUZ0glPEssoIzP6-wuowpBE\" \/>\n\t<meta name=\"p:domain_verify\" content=\"8e0f6da98f8a6d199e5a79f7c743a72d\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/keruanima.com\/en\/marketing-digital\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Keruanima\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Reduflaci\u00f3n y \u00abestiraflaci\u00f3n\u00bb: El gasto en alza perpetuo - Keruanima\" \/>\n\t\t<meta property=\"og:description\" content=\"Analisis y cr\u00edtica a dos vertienes o metodolog\u00edas con las que las compa\u00f1\u00edas aumentan sus beneficios por venta de unidad de producto.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/keruanima.com\/en\/marketing-digital\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/keruanima.com\/wp-content\/uploads\/2019\/08\/cropped-LinkedInCoverColor.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/keruanima.com\/wp-content\/uploads\/2019\/08\/cropped-LinkedInCoverColor.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"769\" \/>\n\t\t<meta property=\"og:image:height\" content=\"376\" \/>\n\t\t<meta property=\"article:tag\" content=\"cr\u00edtica\" \/>\n\t\t<meta property=\"article:tag\" content=\"malas estrat\u00e9gias\" \/>\n\t\t<meta property=\"article:tag\" content=\"marketing\" \/>\n\t\t<meta property=\"article:tag\" content=\"opini\u00f3n\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-09-24T18:01:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-09-25T07:25:58+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Keruanima\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@keruanima\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Reduflaci\u00f3n y \u00abestiraflaci\u00f3n\u00bb: El gasto en alza perpetuo - Keruanima\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Analisis y cr\u00edtica a dos vertienes o metodolog\u00edas con las que las compa\u00f1\u00edas aumentan sus beneficios por venta de unidad de producto.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@keruanima\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/keruanima.com\/wp-content\/uploads\/2019\/08\/cropped-LinkedInCoverColor.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Keruanima\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/keruanima.com\\\/en\\\/marketing-digital\\\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\\\/#article\",\"name\":\"Reduflaci\\u00f3n y \\u00abestiraflaci\\u00f3n\\u00bb: El gasto en alza perpetuo - Keruanima\",\"headline\":\"Reduflaci\\u00f3n y \\u00abestiraflaci\\u00f3n\\u00bb: El gasto en alza perpetuo\",\"author\":{\"@id\":\"https:\\\/\\\/keruanima.com\\\/en\\\/author\\\/kadmin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/keruanima.com\\\/en\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/keruanima.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/flying-potatochips.jpg\",\"width\":640,\"height\":640},\"datePublished\":\"2024-09-24T18:01:00+00:00\",\"dateModified\":\"2024-09-25T07:25:58+00:00\",\"inLanguage\":\"en-GB\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/keruanima.com\\\/en\\\/marketing-digital\\\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/keruanima.com\\\/en\\\/marketing-digital\\\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\\\/#webpage\"},\"articleSection\":\"marketing digital, opini\\u00f3n y cr\\u00edtica, cr\\u00edtica, malas estrat\\u00e9gias, marketing, opini\\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/keruanima.com\\\/en\\\/marketing-digital\\\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/keruanima.com\\\/en#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/keruanima.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/keruanima.com\\\/en\\\/category\\\/marketing-digital\\\/#listItem\",\"name\":\"marketing digital\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/keruanima.com\\\/en\\\/category\\\/marketing-digital\\\/#listItem\",\"position\":2,\"name\":\"marketing digital\",\"item\":\"https:\\\/\\\/keruanima.com\\\/en\\\/category\\\/marketing-digital\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/keruanima.com\\\/en\\\/marketing-digital\\\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\\\/#listItem\",\"name\":\"Reduflaci\\u00f3n y \\u00abestiraflaci\\u00f3n\\u00bb: El gasto en alza perpetuo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/keruanima.com\\\/en#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/keruanima.com\\\/en\\\/marketing-digital\\\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\\\/#listItem\",\"position\":3,\"name\":\"Reduflaci\\u00f3n y \\u00abestiraflaci\\u00f3n\\u00bb: El gasto en alza perpetuo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/keruanima.com\\\/en\\\/category\\\/marketing-digital\\\/#listItem\",\"name\":\"marketing digital\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/keruanima.com\\\/en\\\/#person\",\"name\":\"Keruanima\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/keruanima.com\\\/en\\\/marketing-digital\\\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\\\/#personImage\",\"url\":\"https:\\\/\\\/keruanima.com\\\/wp-content\\\/litespeed\\\/avatar\\\/a404ba2ad8f05ecd81c7791566fc171b.jpg?ver=1788262885\",\"width\":96,\"height\":96,\"caption\":\"Keruanima\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/keruanima.com\\\/en\\\/author\\\/kadmin\\\/#author\",\"url\":\"https:\\\/\\\/keruanima.com\\\/en\\\/author\\\/kadmin\\\/\",\"name\":\"Keruanima\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/keruanima.com\\\/en\\\/marketing-digital\\\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\\\/#authorImage\",\"url\":\"https:\\\/\\\/keruanima.com\\\/wp-content\\\/litespeed\\\/avatar\\\/a404ba2ad8f05ecd81c7791566fc171b.jpg?ver=1788262885\",\"width\":96,\"height\":96,\"caption\":\"Keruanima\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/keruanima.com\\\/en\\\/marketing-digital\\\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\\\/#webpage\",\"url\":\"https:\\\/\\\/keruanima.com\\\/en\\\/marketing-digital\\\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\\\/\",\"name\":\"Reduflaci\\u00f3n y \\u00abestiraflaci\\u00f3n\\u00bb: El gasto en alza perpetuo - Keruanima\",\"description\":\"Analisis y cr\\u00edtica a dos vertienes o metodolog\\u00edas con las que las compa\\u00f1\\u00edas aumentan sus beneficios por venta de unidad de producto.\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/keruanima.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/keruanima.com\\\/en\\\/marketing-digital\\\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/keruanima.com\\\/en\\\/author\\\/kadmin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/keruanima.com\\\/en\\\/author\\\/kadmin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/keruanima.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/flying-potatochips.jpg\",\"@id\":\"https:\\\/\\\/keruanima.com\\\/en\\\/marketing-digital\\\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\\\/#mainImage\",\"width\":640,\"height\":640},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/keruanima.com\\\/en\\\/marketing-digital\\\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\\\/#mainImage\"},\"datePublished\":\"2024-09-24T18:01:00+00:00\",\"dateModified\":\"2024-09-25T07:25:58+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/keruanima.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/keruanima.com\\\/en\\\/\",\"name\":\"Keruanima - Dise\\u00f1ador (\\ud83c\\udf9e\\ufe0fedici\\u00f3n | \\ud83d\\udd79\\ufe0fvideojuegos | \\ud83d\\udd8c\\ufe0fdise\\u00f1o gr\\u00e1fico | \\ud83d\\udcbb web | \\ud83d\\uddbc\\ufe0f arte)\",\"alternateName\":\"Keruanima - Dise\\u00f1ador\",\"description\":\"Creativo y dise\\u00f1ador digital\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/keruanima.com\\\/en\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Reduflaci\u00f3n y \u00abestiraflaci\u00f3n\u00bb: El gasto en alza perpetuo - Keruanima","description":"Analisis y cr\u00edtica a dos vertienes o metodolog\u00edas con las que las compa\u00f1\u00edas aumentan sus beneficios por venta de unidad de producto.","canonical_url":"https:\/\/keruanima.com\/en\/marketing-digital\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"DLdPqYVuvlPaTjY91_F7mUZ0glPEssoIzP6-wuowpBE","p:domain_verify":"8e0f6da98f8a6d199e5a79f7c743a72d","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/keruanima.com\/en\/marketing-digital\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\/#article","name":"Reduflaci\u00f3n y \u00abestiraflaci\u00f3n\u00bb: El gasto en alza perpetuo - Keruanima","headline":"Reduflaci\u00f3n y \u00abestiraflaci\u00f3n\u00bb: El gasto en alza perpetuo","author":{"@id":"https:\/\/keruanima.com\/en\/author\/kadmin\/#author"},"publisher":{"@id":"https:\/\/keruanima.com\/en\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/keruanima.com\/wp-content\/uploads\/2024\/09\/flying-potatochips.jpg","width":640,"height":640},"datePublished":"2024-09-24T18:01:00+00:00","dateModified":"2024-09-25T07:25:58+00:00","inLanguage":"en-GB","mainEntityOfPage":{"@id":"https:\/\/keruanima.com\/en\/marketing-digital\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\/#webpage"},"isPartOf":{"@id":"https:\/\/keruanima.com\/en\/marketing-digital\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\/#webpage"},"articleSection":"marketing digital, opini\u00f3n y cr\u00edtica, cr\u00edtica, malas estrat\u00e9gias, marketing, opini\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/keruanima.com\/en\/marketing-digital\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/keruanima.com\/en#listItem","position":1,"name":"Inicio","item":"https:\/\/keruanima.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/keruanima.com\/en\/category\/marketing-digital\/#listItem","name":"marketing digital"}},{"@type":"ListItem","@id":"https:\/\/keruanima.com\/en\/category\/marketing-digital\/#listItem","position":2,"name":"marketing digital","item":"https:\/\/keruanima.com\/en\/category\/marketing-digital\/","nextItem":{"@type":"ListItem","@id":"https:\/\/keruanima.com\/en\/marketing-digital\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\/#listItem","name":"Reduflaci\u00f3n y \u00abestiraflaci\u00f3n\u00bb: El gasto en alza perpetuo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/keruanima.com\/en#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/keruanima.com\/en\/marketing-digital\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\/#listItem","position":3,"name":"Reduflaci\u00f3n y \u00abestiraflaci\u00f3n\u00bb: El gasto en alza perpetuo","previousItem":{"@type":"ListItem","@id":"https:\/\/keruanima.com\/en\/category\/marketing-digital\/#listItem","name":"marketing digital"}}]},{"@type":"Person","@id":"https:\/\/keruanima.com\/en\/#person","name":"Keruanima","image":{"@type":"ImageObject","@id":"https:\/\/keruanima.com\/en\/marketing-digital\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\/#personImage","url":"https:\/\/keruanima.com\/wp-content\/litespeed\/avatar\/a404ba2ad8f05ecd81c7791566fc171b.jpg?ver=1788262885","width":96,"height":96,"caption":"Keruanima"}},{"@type":"Person","@id":"https:\/\/keruanima.com\/en\/author\/kadmin\/#author","url":"https:\/\/keruanima.com\/en\/author\/kadmin\/","name":"Keruanima","image":{"@type":"ImageObject","@id":"https:\/\/keruanima.com\/en\/marketing-digital\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\/#authorImage","url":"https:\/\/keruanima.com\/wp-content\/litespeed\/avatar\/a404ba2ad8f05ecd81c7791566fc171b.jpg?ver=1788262885","width":96,"height":96,"caption":"Keruanima"}},{"@type":"WebPage","@id":"https:\/\/keruanima.com\/en\/marketing-digital\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\/#webpage","url":"https:\/\/keruanima.com\/en\/marketing-digital\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\/","name":"Reduflaci\u00f3n y \u00abestiraflaci\u00f3n\u00bb: El gasto en alza perpetuo - Keruanima","description":"Analisis y cr\u00edtica a dos vertienes o metodolog\u00edas con las que las compa\u00f1\u00edas aumentan sus beneficios por venta de unidad de producto.","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/keruanima.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/keruanima.com\/en\/marketing-digital\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\/#breadcrumblist"},"author":{"@id":"https:\/\/keruanima.com\/en\/author\/kadmin\/#author"},"creator":{"@id":"https:\/\/keruanima.com\/en\/author\/kadmin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/keruanima.com\/wp-content\/uploads\/2024\/09\/flying-potatochips.jpg","@id":"https:\/\/keruanima.com\/en\/marketing-digital\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\/#mainImage","width":640,"height":640},"primaryImageOfPage":{"@id":"https:\/\/keruanima.com\/en\/marketing-digital\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\/#mainImage"},"datePublished":"2024-09-24T18:01:00+00:00","dateModified":"2024-09-25T07:25:58+00:00"},{"@type":"WebSite","@id":"https:\/\/keruanima.com\/en\/#website","url":"https:\/\/keruanima.com\/en\/","name":"Keruanima - Dise\u00f1ador (\ud83c\udf9e\ufe0fedici\u00f3n | \ud83d\udd79\ufe0fvideojuegos | \ud83d\udd8c\ufe0fdise\u00f1o gr\u00e1fico | \ud83d\udcbb web | \ud83d\uddbc\ufe0f arte)","alternateName":"Keruanima - Dise\u00f1ador","description":"Creativo y dise\u00f1ador digital","inLanguage":"en-GB","publisher":{"@id":"https:\/\/keruanima.com\/en\/#person"}}]},"og:locale":"en_GB","og:site_name":"Keruanima","og:type":"article","og:title":"Reduflaci\u00f3n y \u00abestiraflaci\u00f3n\u00bb: El gasto en alza perpetuo - Keruanima","og:description":"Analisis y cr\u00edtica a dos vertienes o metodolog\u00edas con las que las compa\u00f1\u00edas aumentan sus beneficios por venta de unidad de producto.","og:url":"https:\/\/keruanima.com\/en\/marketing-digital\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\/","og:image":"https:\/\/keruanima.com\/wp-content\/uploads\/2019\/08\/cropped-LinkedInCoverColor.jpg","og:image:secure_url":"https:\/\/keruanima.com\/wp-content\/uploads\/2019\/08\/cropped-LinkedInCoverColor.jpg","og:image:width":769,"og:image:height":376,"article:tag":["cr\u00edtica","malas estrat\u00e9gias","marketing","opini\u00f3n"],"article:published_time":"2024-09-24T18:01:00+00:00","article:modified_time":"2024-09-25T07:25:58+00:00","article:publisher":"https:\/\/www.facebook.com\/Keruanima","twitter:card":"summary_large_image","twitter:site":"@keruanima","twitter:title":"Reduflaci\u00f3n y \u00abestiraflaci\u00f3n\u00bb: El gasto en alza perpetuo - Keruanima","twitter:description":"Analisis y cr\u00edtica a dos vertienes o metodolog\u00edas con las que las compa\u00f1\u00edas aumentan sus beneficios por venta de unidad de producto.","twitter:creator":"@keruanima","twitter:image":"https:\/\/keruanima.com\/wp-content\/uploads\/2019\/08\/cropped-LinkedInCoverColor.jpg","twitter:label1":"Written by","twitter:data1":"Keruanima","twitter:label2":"Est. reading time","twitter:data2":"4 minutes"},"aioseo_meta_data":{"post_id":"3577","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-09-24 13:17:06","updated":"2025-06-04 02:14:05","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/keruanima.com\/en\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/keruanima.com\/en\/category\/marketing-digital\/\" title=\"marketing digital\">marketing digital<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tReduflaci\u00f3n y \u00abestiraflaci\u00f3n\u00bb: El gasto en alza perpetuo\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/keruanima.com\/en"},{"label":"marketing digital","link":"https:\/\/keruanima.com\/en\/category\/marketing-digital\/"},{"label":"Reduflaci\u00f3n y \u00abestiraflaci\u00f3n\u00bb: El gasto en alza perpetuo","link":"https:\/\/keruanima.com\/en\/marketing-digital\/reduflacion-y-estiraflacion-el-gasto-en-alza-perpetuo\/"}],"_links":{"self":[{"href":"https:\/\/keruanima.com\/en\/wp-json\/wp\/v2\/posts\/3577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/keruanima.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/keruanima.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/keruanima.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/keruanima.com\/en\/wp-json\/wp\/v2\/comments?post=3577"}],"version-history":[{"count":4,"href":"https:\/\/keruanima.com\/en\/wp-json\/wp\/v2\/posts\/3577\/revisions"}],"predecessor-version":[{"id":3587,"href":"https:\/\/keruanima.com\/en\/wp-json\/wp\/v2\/posts\/3577\/revisions\/3587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/keruanima.com\/en\/wp-json\/wp\/v2\/media\/3584"}],"wp:attachment":[{"href":"https:\/\/keruanima.com\/en\/wp-json\/wp\/v2\/media?parent=3577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/keruanima.com\/en\/wp-json\/wp\/v2\/categories?post=3577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/keruanima.com\/en\/wp-json\/wp\/v2\/tags?post=3577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}